{"id":24247,"date":"2019-11-28T16:24:04","date_gmt":"2019-11-28T14:24:04","guid":{"rendered":"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii"},"modified":"2026-05-07T15:27:05","modified_gmt":"2026-05-07T13:27:05","slug":"fuer-koerperschaften-ii","status":"publish","type":"wpsl_stores","link":"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/","title":{"rendered":"f\u00fcr K\u00f6rperschaften II"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","wpsl_store_category":[1501],"class_list":["post-24247","wpsl_stores","type-wpsl_stores","status-publish","hentry","wpsl_store_category-berlin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Finanzamt f\u00fcr K\u00f6rperschaften II: \u00d6ffnungszeiten, Adresse &amp; Telefon<\/title>\n<meta name=\"description\" content=\"Informationen zum Finanzamt f\u00fcr K\u00f6rperschaften II mit der Finanzamtsnummer 1137 auf einem Blick &gt; Adresse, Telefon \u260e, \u00d6ffnungszeiten!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"f\u00fcr K\u00f6rperschaften II\" \/>\n<meta property=\"og:description\" content=\"Informationen zum Finanzamt f\u00fcr K\u00f6rperschaften II mit der Finanzamtsnummer 1137 auf einem Blick &gt; Adresse, Telefon \u260e, \u00d6ffnungszeiten!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"smartsteuer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/smartsteuer\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T13:27:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@smartsteuer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/finanzamt\\\/fuer-koerperschaften-ii\\\/\",\"url\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/finanzamt\\\/fuer-koerperschaften-ii\\\/\",\"name\":\"Finanzamt f\u00fcr K\u00f6rperschaften II: \u00d6ffnungszeiten, Adresse & Telefon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#website\"},\"datePublished\":\"2019-11-28T14:24:04+00:00\",\"dateModified\":\"2026-05-07T13:27:05+00:00\",\"description\":\"Informationen zum Finanzamt f\u00fcr K\u00f6rperschaften II mit der Finanzamtsnummer 1137 auf einem Blick > Adresse, Telefon \u260e, \u00d6ffnungszeiten!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/finanzamt\\\/fuer-koerperschaften-ii\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/finanzamt\\\/fuer-koerperschaften-ii\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/finanzamt\\\/fuer-koerperschaften-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"f\u00fcr K\u00f6rperschaften II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#website\",\"url\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/\",\"name\":\"smartsteuer\",\"description\":\"Steuererkl\u00e4rung 2024 online machen &amp; Steuern sparen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#organization\",\"name\":\"smartsteuer GmbH\",\"url\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Favicon-smartsteuer.png\",\"contentUrl\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Favicon-smartsteuer.png\",\"width\":512,\"height\":512,\"caption\":\"smartsteuer GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/smartsteuer\\\/\",\"https:\\\/\\\/x.com\\\/smartsteuer\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCu02GkFNrMRzwysT2SEmNrQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finanzamt f\u00fcr K\u00f6rperschaften II: \u00d6ffnungszeiten, Adresse & Telefon","description":"Informationen zum Finanzamt f\u00fcr K\u00f6rperschaften II mit der Finanzamtsnummer 1137 auf einem Blick > Adresse, Telefon \u260e, \u00d6ffnungszeiten!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/","og_locale":"de_DE","og_type":"article","og_title":"f\u00fcr K\u00f6rperschaften II","og_description":"Informationen zum Finanzamt f\u00fcr K\u00f6rperschaften II mit der Finanzamtsnummer 1137 auf einem Blick > Adresse, Telefon \u260e, \u00d6ffnungszeiten!","og_url":"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/","og_site_name":"smartsteuer","article_publisher":"https:\/\/de-de.facebook.com\/smartsteuer\/","article_modified_time":"2026-05-07T13:27:05+00:00","twitter_card":"summary_large_image","twitter_site":"@smartsteuer","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/","url":"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/","name":"Finanzamt f\u00fcr K\u00f6rperschaften II: \u00d6ffnungszeiten, Adresse & Telefon","isPartOf":{"@id":"https:\/\/www.smartsteuer.de\/online\/#website"},"datePublished":"2019-11-28T14:24:04+00:00","dateModified":"2026-05-07T13:27:05+00:00","description":"Informationen zum Finanzamt f\u00fcr K\u00f6rperschaften II mit der Finanzamtsnummer 1137 auf einem Blick > Adresse, Telefon \u260e, \u00d6ffnungszeiten!","breadcrumb":{"@id":"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.smartsteuer.de\/online\/finanzamt\/fuer-koerperschaften-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smartsteuer.de\/online\/"},{"@type":"ListItem","position":2,"name":"f\u00fcr K\u00f6rperschaften II"}]},{"@type":"WebSite","@id":"https:\/\/www.smartsteuer.de\/online\/#website","url":"https:\/\/www.smartsteuer.de\/online\/","name":"smartsteuer","description":"Steuererkl\u00e4rung 2024 online machen &amp; Steuern sparen","publisher":{"@id":"https:\/\/www.smartsteuer.de\/online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smartsteuer.de\/online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.smartsteuer.de\/online\/#organization","name":"smartsteuer GmbH","url":"https:\/\/www.smartsteuer.de\/online\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.smartsteuer.de\/online\/#\/schema\/logo\/image\/","url":"https:\/\/www.smartsteuer.de\/online\/wp-content\/uploads\/2024\/11\/Favicon-smartsteuer.png","contentUrl":"https:\/\/www.smartsteuer.de\/online\/wp-content\/uploads\/2024\/11\/Favicon-smartsteuer.png","width":512,"height":512,"caption":"smartsteuer GmbH"},"image":{"@id":"https:\/\/www.smartsteuer.de\/online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/smartsteuer\/","https:\/\/x.com\/smartsteuer","https:\/\/www.youtube.com\/channel\/UCu02GkFNrMRzwysT2SEmNrQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.smartsteuer.de\/online\/wp-json\/wp\/v2\/wpsl_stores\/24247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smartsteuer.de\/online\/wp-json\/wp\/v2\/wpsl_stores"}],"about":[{"href":"https:\/\/www.smartsteuer.de\/online\/wp-json\/wp\/v2\/types\/wpsl_stores"}],"version-history":[{"count":1,"href":"https:\/\/www.smartsteuer.de\/online\/wp-json\/wp\/v2\/wpsl_stores\/24247\/revisions"}],"predecessor-version":[{"id":32226,"href":"https:\/\/www.smartsteuer.de\/online\/wp-json\/wp\/v2\/wpsl_stores\/24247\/revisions\/32226"}],"wp:attachment":[{"href":"https:\/\/www.smartsteuer.de\/online\/wp-json\/wp\/v2\/media?parent=24247"}],"wp:term":[{"taxonomy":"wpsl_store_category","embeddable":true,"href":"https:\/\/www.smartsteuer.de\/online\/wp-json\/wp\/v2\/wpsl_store_category?post=24247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}